{"id":36752,"date":"2017-06-08T12:12:58","date_gmt":"2017-06-08T10:12:58","guid":{"rendered":"http:\/\/rede.acampa.eu\/?p=36752"},"modified":"2018-03-27T10:30:18","modified_gmt":"2018-03-27T08:30:18","slug":"a-revista-luzes-saca-un-numero-especial-o-imperio-da-ruindade","status":"publish","type":"post","link":"https:\/\/blog.redeacampa.org\/gl\/a-revista-luzes-saca-un-numero-especial-o-imperio-da-ruindade\/","title":{"rendered":"A revista LUZES saca un n\u00famero especial, \u201cO imperio da ruindade\u201d"},"content":{"rendered":"<p>Coincidindo con Acampa 2017 a revista <a href=\"http:\/\/revistaluzes.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">LUZES<\/a> saca un n\u00famero especial, \u201c<strong>O imperio da ruindade<\/strong>\u201d, dedicado aos refuxiados e ao rearmamento global.<\/p>\n<p>Cont\u00e9n reportaxes sobre a situaci\u00f3n dos menores nos conflitos, as esperanzas rotas dos solicitantes de asirlo en Europa, As ru\u00ednas de Sabratha (unha viaxe mental polo conflito libio), o Kurdist\u00e1n (refuxiados na s\u00faa propia terra) e informes sobre o gasto en defensa presente e proxectado nos EUA, Europa e Espa\u00f1a.<\/p>\n<p>O t\u00edtulo deste <a href=\"http:\/\/revistaluzes.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">LUZES<\/a> 44 \u00e9 \u201c<strong>O imperio da ruindade<\/strong>\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coincidindo con Acampa 2017 a revista LUZES saca un n\u00famero especial, \u201cO imperio da ruindade\u201d, dedicado aos refuxiados e ao rearmamento global. Cont\u00e9n reportaxes sobre a situaci\u00f3n dos menores nos conflitos, as esperanzas rotas dos solicitantes de asirlo en Europa, As ru\u00ednas de Sabratha (unha viaxe mental polo conflito libio), o Kurdist\u00e1n (refuxiados na s\u00faa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":35722,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[25],"tags":[30,36],"class_list":["post-36752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novas","tag-colaboracions-gl","tag-revistas-gl"],"_links":{"self":[{"href":"https:\/\/blog.redeacampa.org\/gl\/wp-json\/wp\/v2\/posts\/36752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.redeacampa.org\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.redeacampa.org\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.redeacampa.org\/gl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.redeacampa.org\/gl\/wp-json\/wp\/v2\/comments?post=36752"}],"version-history":[{"count":0,"href":"https:\/\/blog.redeacampa.org\/gl\/wp-json\/wp\/v2\/posts\/36752\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.redeacampa.org\/gl\/wp-json\/wp\/v2\/media\/35722"}],"wp:attachment":[{"href":"https:\/\/blog.redeacampa.org\/gl\/wp-json\/wp\/v2\/media?parent=36752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.redeacampa.org\/gl\/wp-json\/wp\/v2\/categories?post=36752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.redeacampa.org\/gl\/wp-json\/wp\/v2\/tags?post=36752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}